{"id":7226,"date":"2025-03-14T10:18:44","date_gmt":"2025-03-14T03:18:44","guid":{"rendered":"https:\/\/vcube.co.id\/?page_id=7226"},"modified":"2026-04-10T08:52:21","modified_gmt":"2026-04-10T01:52:21","slug":"phone","status":"publish","type":"page","link":"https:\/\/vcube.co.id\/en\/zoom\/phone\/","title":{"rendered":"Zoom Phone"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"7226\" class=\"elementor elementor-7226\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-72a3c61 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"72a3c61\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-36134b3\" data-id=\"36134b3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0df998b elementor-mobile-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"0df998b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"28\" height=\"29\" viewBox=\"0 0 28 29\" fill=\"none\"><path d=\"M28 15C28 16.4971 27.8796 17.9651 27.6497 19.3965C26.8886 24.1351 23.1351 27.8886 18.3965 28.6497C16.965 28.8796 15.497 29 14 29C12.503 29 11.035 28.8796 9.60355 28.6497C4.86494 27.8886 1.11135 24.1351 0.350273 19.3965C0.120366 17.9651 0 16.4971 0 15C0 13.5029 0.120366 12.0349 0.350273 10.6035C1.11135 5.86489 4.86494 2.11135 9.60355 1.35027C11.035 1.12036 12.503 1 14 1C15.497 1 16.965 1.12036 18.3965 1.35027C23.1351 2.11135 26.8886 5.86489 27.6497 10.6035C27.8796 12.0349 28 13.5029 28 15Z\" fill=\"#0B5CFF\"><\/path><path d=\"M28 15C28 16.4971 27.8796 17.9651 27.6497 19.3965C26.8886 24.1351 23.1351 27.8886 18.3965 28.6497C16.965 28.8796 15.497 29 14 29C12.503 29 11.035 28.8796 9.60355 28.6497C4.86494 27.8886 1.11135 24.1351 0.350273 19.3965C0.120366 17.9651 0 16.4971 0 15C0 13.5029 0.120366 12.0349 0.350273 10.6035C1.11135 5.86489 4.86494 2.11135 9.60355 1.35027C11.035 1.12036 12.503 1 14 1C15.497 1 16.965 1.12036 18.3965 1.35027C23.1351 2.11135 26.8886 5.86489 27.6497 10.6035C27.8796 12.0349 28 13.5029 28 15Z\" fill=\"url(#paint0_radial_918_8344)\"><\/path><path d=\"M27.9999 15C27.9999 16.4971 27.8796 17.9651 27.6497 19.3965C26.8885 24.1351 23.135 27.8886 18.3964 28.6497C16.965 28.8796 15.497 29 14 29C12.503 29 11.0349 28.8796 9.60353 28.6497C4.86487 27.8886 1.11133 24.1351 0.350254 19.3965C0.120346 17.965 3.05176e-05 16.4971 3.05176e-05 15C3.05176e-05 13.503 0.120346 12.0349 0.350254 10.6034C1.11138 5.86489 4.86492 2.11125 9.60353 1.35022C11.035 1.12032 12.5029 1 14 1C15.497 1 16.965 1.12032 18.3964 1.35022C23.135 2.11125 26.8886 5.86489 27.6497 10.6034C27.8796 12.0349 27.9999 13.5029 27.9999 15Z\" fill=\"url(#paint1_radial_918_8344)\"><\/path><g clip-path=\"url(#clip0_918_8344)\"><path d=\"M21 18.0625V19.3749C21 20.818 19.8335 21.9871 18.391 21.998V22C18.3866 22 18.3823 21.9993 18.3779 21.9993C18.3756 21.9993 18.3735 22 18.3713 22V21.999C12.0958 21.9882 7.0103 16.911 7 10.6442C6.99761 9.1906 8.17307 8 9.62872 8H10.943C11.9108 8 12.6955 8.7835 12.6955 9.75001V10.7751C12.6955 11.2392 12.5108 11.6844 12.1821 12.0126L11.2627 12.9308C11.0776 13.1157 11.0119 13.3964 11.1122 13.6378C11.909 15.5556 13.4405 17.0876 15.3589 17.8871C15.601 17.988 15.8827 17.9225 16.0682 17.7373L16.9817 16.8251C17.3103 16.4969 17.756 16.3125 18.2208 16.3125H19.2475C20.2154 16.3125 21 17.096 21 18.0625Z\" fill=\"white\"><\/path><\/g><defs><radialGradient id=\"paint0_radial_918_8344\" cx=\"0\" cy=\"0\" r=\"1\" gradientUnits=\"userSpaceOnUse\" gradientTransform=\"translate(14 13.3731) scale(18.8757 15.7759)\"><stop offset=\"0.82\" stop-color=\"#0B5CFF\" stop-opacity=\"0\"><\/stop><stop offset=\"0.98\" stop-color=\"#003CB3\"><\/stop><\/radialGradient><radialGradient id=\"paint1_radial_918_8344\" cx=\"0\" cy=\"0\" r=\"1\" gradientUnits=\"userSpaceOnUse\" gradientTransform=\"translate(14 16.6211) scale(18.8689 15.7702)\"><stop offset=\"0.8\" stop-color=\"#0B5CFF\" stop-opacity=\"0\"><\/stop><stop offset=\"1\" stop-color=\"#71A5F1\"><\/stop><\/radialGradient><clipPath id=\"clip0_918_8344\"><rect width=\"18\" height=\"18\" fill=\"white\" transform=\"translate(5 6)\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Zoom Phone<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36bce0e elementor-widget elementor-widget-heading\" data-id=\"36bce0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Cloud PBX \/ Layanan Telepon Cloud<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1a0eee elementor-widget elementor-widget-heading\" data-id=\"a1a0eee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Zoom Phone<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b6b31d5 elementor-widget elementor-widget-text-editor\" data-id=\"b6b31d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Panggilan telepon berkualitas tinggi dan beragam fitur. Wujudkan era baru telepon bisnis sambil menekan biaya.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca49ae0 elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"ca49ae0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#phone\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Selengkapnya<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3927b01\" data-id=\"3927b01\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd8e2ca elementor-widget elementor-widget-image\" data-id=\"bd8e2ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"673\" src=\"https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/zoom-phone-indonesia-1024x673.webp\" class=\"attachment-large size-large wp-image-7228\" alt=\"Zoom Phone\" srcset=\"https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/zoom-phone-indonesia-1024x673.webp 1024w, https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/zoom-phone-indonesia-300x197.webp 300w, https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/zoom-phone-indonesia-768x505.webp 768w, https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/zoom-phone-indonesia-1536x1010.webp 1536w, https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/zoom-phone-indonesia-18x12.webp 18w, https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/zoom-phone-indonesia.webp 1709w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a95ab9f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a95ab9f\" data-element_type=\"section\" data-e-type=\"section\" id=\"phone\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-15b291d\" data-id=\"15b291d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10d5b8d elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"10d5b8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Saya ingin mengurangi biaya peralatan terkait telepon<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-324ee3b elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"324ee3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Saya ingin mengganti operator tanpa mengubah nomor telepon saya<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-738ee50 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"738ee50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Membangun basis, ingin menggunakan layanan telepon dengan biaya rendah<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5033776 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"5033776\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Saya tidak dapat menjawab atau meneruskan panggilan karena saya bekerja jarak jauh atau di luar kantor.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a72791 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8a72791\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Saya beralih ke cloud PBX tetapi biaya panggilannya ternyata sangat tinggi<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44bdaca elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"44bdaca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Kualitas panggilan berhubungan langsung dengan kepuasan pelanggan<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-649a7f8\" data-id=\"649a7f8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac18bbb elementor-widget elementor-widget-video\" data-id=\"ac18bbb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=xZfCxpVwT6A&quot;,&quot;video_type&quot;:&quot;youtube&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fc84d86 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fc84d86\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-231a6ef\" data-id=\"231a6ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3df119e elementor-align-center elementor-mobile-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"3df119e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"28\" height=\"29\" viewBox=\"0 0 28 29\" fill=\"none\"><path d=\"M28 15C28 16.4971 27.8796 17.9651 27.6497 19.3965C26.8886 24.1351 23.1351 27.8886 18.3965 28.6497C16.965 28.8796 15.497 29 14 29C12.503 29 11.035 28.8796 9.60355 28.6497C4.86494 27.8886 1.11135 24.1351 0.350273 19.3965C0.120366 17.9651 0 16.4971 0 15C0 13.5029 0.120366 12.0349 0.350273 10.6035C1.11135 5.86489 4.86494 2.11135 9.60355 1.35027C11.035 1.12036 12.503 1 14 1C15.497 1 16.965 1.12036 18.3965 1.35027C23.1351 2.11135 26.8886 5.86489 27.6497 10.6035C27.8796 12.0349 28 13.5029 28 15Z\" fill=\"#0B5CFF\"><\/path><path d=\"M28 15C28 16.4971 27.8796 17.9651 27.6497 19.3965C26.8886 24.1351 23.1351 27.8886 18.3965 28.6497C16.965 28.8796 15.497 29 14 29C12.503 29 11.035 28.8796 9.60355 28.6497C4.86494 27.8886 1.11135 24.1351 0.350273 19.3965C0.120366 17.9651 0 16.4971 0 15C0 13.5029 0.120366 12.0349 0.350273 10.6035C1.11135 5.86489 4.86494 2.11135 9.60355 1.35027C11.035 1.12036 12.503 1 14 1C15.497 1 16.965 1.12036 18.3965 1.35027C23.1351 2.11135 26.8886 5.86489 27.6497 10.6035C27.8796 12.0349 28 13.5029 28 15Z\" fill=\"url(#paint0_radial_918_8344)\"><\/path><path d=\"M27.9999 15C27.9999 16.4971 27.8796 17.9651 27.6497 19.3965C26.8885 24.1351 23.135 27.8886 18.3964 28.6497C16.965 28.8796 15.497 29 14 29C12.503 29 11.0349 28.8796 9.60353 28.6497C4.86487 27.8886 1.11133 24.1351 0.350254 19.3965C0.120346 17.965 3.05176e-05 16.4971 3.05176e-05 15C3.05176e-05 13.503 0.120346 12.0349 0.350254 10.6034C1.11138 5.86489 4.86492 2.11125 9.60353 1.35022C11.035 1.12032 12.5029 1 14 1C15.497 1 16.965 1.12032 18.3964 1.35022C23.135 2.11125 26.8886 5.86489 27.6497 10.6034C27.8796 12.0349 27.9999 13.5029 27.9999 15Z\" fill=\"url(#paint1_radial_918_8344)\"><\/path><g clip-path=\"url(#clip0_918_8344)\"><path d=\"M21 18.0625V19.3749C21 20.818 19.8335 21.9871 18.391 21.998V22C18.3866 22 18.3823 21.9993 18.3779 21.9993C18.3756 21.9993 18.3735 22 18.3713 22V21.999C12.0958 21.9882 7.0103 16.911 7 10.6442C6.99761 9.1906 8.17307 8 9.62872 8H10.943C11.9108 8 12.6955 8.7835 12.6955 9.75001V10.7751C12.6955 11.2392 12.5108 11.6844 12.1821 12.0126L11.2627 12.9308C11.0776 13.1157 11.0119 13.3964 11.1122 13.6378C11.909 15.5556 13.4405 17.0876 15.3589 17.8871C15.601 17.988 15.8827 17.9225 16.0682 17.7373L16.9817 16.8251C17.3103 16.4969 17.756 16.3125 18.2208 16.3125H19.2475C20.2154 16.3125 21 17.096 21 18.0625Z\" fill=\"white\"><\/path><\/g><defs><radialGradient id=\"paint0_radial_918_8344\" cx=\"0\" cy=\"0\" r=\"1\" gradientUnits=\"userSpaceOnUse\" gradientTransform=\"translate(14 13.3731) scale(18.8757 15.7759)\"><stop offset=\"0.82\" stop-color=\"#0B5CFF\" stop-opacity=\"0\"><\/stop><stop offset=\"0.98\" stop-color=\"#003CB3\"><\/stop><\/radialGradient><radialGradient id=\"paint1_radial_918_8344\" cx=\"0\" cy=\"0\" r=\"1\" gradientUnits=\"userSpaceOnUse\" gradientTransform=\"translate(14 16.6211) scale(18.8689 15.7702)\"><stop offset=\"0.8\" stop-color=\"#0B5CFF\" stop-opacity=\"0\"><\/stop><stop offset=\"1\" stop-color=\"#71A5F1\"><\/stop><\/radialGradient><clipPath id=\"clip0_918_8344\"><rect width=\"18\" height=\"18\" fill=\"white\" transform=\"translate(5 6)\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Zoom Phone<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e89c70 elementor-widget elementor-widget-heading\" data-id=\"5e89c70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Apa itu Zoom Phone?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97b8b3d elementor-widget elementor-widget-text-editor\" data-id=\"97b8b3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Zoom Phone adalah sistem telepon berbasis cloud yang dirancang untuk mendukung komunikasi bisnis dengan lebih efisien dan fleksibel. Dengan fitur canggih seperti panggilan VoIP berkualitas tinggi, integrasi dengan aplikasi bisnis, dan skalabilitas yang mudah, Zoom Phone menjadi pilihan ideal bagi perusahaan yang ingin meningkatkan produktivitas tim dan efisiensi operasional.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f0a2e67 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f0a2e67\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-b7f56da\" data-id=\"b7f56da\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-faf5ad7 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"faf5ad7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"500\" height=\"317\" src=\"https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-Hemat-Biaya.webp\" class=\"attachment-full size-full wp-image-7242\" alt=\"\" srcset=\"https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-Hemat-Biaya.webp 500w, https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-Hemat-Biaya-300x190.webp 300w, https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-Hemat-Biaya-18x12.webp 18w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Hemat Biaya<\/h3><p class=\"elementor-image-box-description\">Tidak perlu investasi perangkat keras mahal seperti sistem telepon konvensional.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-6e06444\" data-id=\"6e06444\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ad71b1 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"1ad71b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"500\" height=\"317\" src=\"https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-Multi-Perangkat.webp\" class=\"attachment-full size-full wp-image-7244\" alt=\"\" srcset=\"https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-Multi-Perangkat.webp 500w, https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-Multi-Perangkat-300x190.webp 300w, https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-Multi-Perangkat-18x12.webp 18w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Fleksibilitas Tinggi<\/h3><p class=\"elementor-image-box-description\">Dapat digunakan di berbagai perangkat: desktop, laptop, tablet, dan smartphone.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-e7ddd12\" data-id=\"e7ddd12\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b35634 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"5b35634\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"317\" src=\"https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-Simple.webp\" class=\"attachment-full size-full wp-image-7245\" alt=\"Zoom Phone - Simple\" srcset=\"https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-Simple.webp 500w, https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-Simple-300x190.webp 300w, https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-Simple-18x12.webp 18w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Menyederhanakan Operasi<\/h3><p class=\"elementor-image-box-description\">Menyederhanakan operasi dengan menggabungkannya ke dalam aplikasi zoom<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-7b9ee18\" data-id=\"7b9ee18\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d6b769 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"6d6b769\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"317\" src=\"https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-Kualitas-Tinggi.webp\" class=\"attachment-full size-full wp-image-7243\" alt=\"Zoom Phone - Kualitas Tinggi\" srcset=\"https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-Kualitas-Tinggi.webp 500w, https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-Kualitas-Tinggi-300x190.webp 300w, https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-Kualitas-Tinggi-18x12.webp 18w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Kualitas Tinggi<\/h3><p class=\"elementor-image-box-description\">Nikmati panggilan suara jernih dengan teknologi VoIP yang canggih.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4da6318 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4da6318\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e45e699\" data-id=\"e45e699\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d2e01b5 elementor-widget elementor-widget-heading\" data-id=\"d2e01b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Di era saat cloud PBX menjadi hal yang lumrah, apakah Anda masih menggunakan telepon rumah dan terus membayar biayanya?<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c183f6 elementor-widget elementor-widget-text-editor\" data-id=\"5c183f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tDengan Cloud PBX, semua fungsi peralatan khusus yang sebelumnya harus dibeli, dipasang, dan dikelola secara internal ditangani di cloud. Tidak perlu membeli perangkat keras dasar, dan dengan mendaftar untuk paket panggilan dengan tarif tetap, Anda dapat menetapkan biaya panggilan Anda. Nomor telepon juga dapat dikeluarkan dengan biaya rendah. Portabilitas nomor juga didukung, sehingga Anda dapat terus menggunakan nomor telepon Anda saat ini tanpa harus mengubahnya.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-92d6fdc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"92d6fdc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8da984d\" data-id=\"8da984d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8febaf6 elementor-widget elementor-widget-text-editor\" data-id=\"8febaf6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-pm-slice=\"1 1 []\">Contoh biaya yang dapat Anda hemat dengan Zoom Phone<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1973b85 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1973b85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Biaya pemasangan dan pemeliharaan untuk unit utama dan peralatan PBX<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Biaya dasar operator telepon tetap &amp; biaya panggilan yang dibebankan per panggilan<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Biaya Smartphone<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Biaya komunikasi dasar operator telepon &amp; biaya per panggilan<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f7f2a66\" data-id=\"f7f2a66\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69c3ba1 elementor-widget elementor-widget-image\" data-id=\"69c3ba1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"394\" src=\"https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Telepon-Konvensional-vs-Cloud-PBX.webp\" class=\"attachment-large size-large wp-image-7260\" alt=\"Telepon Konvensional vs Cloud PBX\" srcset=\"https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Telepon-Konvensional-vs-Cloud-PBX.webp 800w, https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Telepon-Konvensional-vs-Cloud-PBX-300x148.webp 300w, https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Telepon-Konvensional-vs-Cloud-PBX-768x378.webp 768w, https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Telepon-Konvensional-vs-Cloud-PBX-18x9.webp 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d7be6df elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d7be6df\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eacfb41\" data-id=\"eacfb41\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-faa5978 elementor-widget elementor-widget-heading\" data-id=\"faa5978\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Anda dapat membuat dan menerima panggilan dari PC atau ponsel pintar Anda!\nAnda dapat menggunakan saluran telepon yang sama antar pangkalan bahkan saat bekerja dari jarak jauh.<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f2d03bc elementor-widget elementor-widget-text-editor\" data-id=\"f2d03bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dengan Cloud PBX, setiap perangkat terhubung ke PBX melalui Internet, sehingga<br \/>Anda dapat menggunakan nomor telepon bersama di mana pun Anda berada.<br \/>Nomor utama dan nomor departemen dapat ditetapkan untuk berbagai keperluan, memungkinkan pengoperasian yang fleksibel seperti pengoperasian meja bantuan jarak jauh.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5a3bbca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5a3bbca\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-e9aea08\" data-id=\"e9aea08\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32f1b13 elementor-widget elementor-widget-image\" data-id=\"32f1b13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-work-shifts.webp\" class=\"attachment-large size-large wp-image-7275\" alt=\"Zoom Phone - work shifts\" srcset=\"https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-work-shifts.webp 400w, https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-work-shifts-300x300.webp 300w, https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-work-shifts-150x150.webp 150w, https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-work-shifts-12x12.webp 12w, https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-work-shifts-50x50.webp 50w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7fac6e2\" data-id=\"7fac6e2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b5c8537 elementor-widget elementor-widget-image\" data-id=\"b5c8537\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-Working-remotely.webp\" class=\"attachment-large size-large wp-image-7276\" alt=\"Zoom Phone - Working remotely\" srcset=\"https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-Working-remotely.webp 400w, https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-Working-remotely-300x300.webp 300w, https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-Working-remotely-150x150.webp 150w, https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-Working-remotely-12x12.webp 12w, https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-Working-remotely-50x50.webp 50w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-bf8801e\" data-id=\"bf8801e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb9304a elementor-widget elementor-widget-image\" data-id=\"fb9304a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-business.webp\" class=\"attachment-large size-large wp-image-7277\" alt=\"Zoom Phone - business\" srcset=\"https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-business.webp 400w, https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-business-300x300.webp 300w, https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-business-150x150.webp 150w, https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-business-12x12.webp 12w, https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-business-50x50.webp 50w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a0f1a15 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a0f1a15\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-87fd094\" data-id=\"87fd094\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a9404b1 elementor-widget elementor-widget-heading\" data-id=\"a9404b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Fitur utama Zoom Phone<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-806cde1 elementor-widget elementor-widget-text-editor\" data-id=\"806cde1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table id=\"zp_function_table\" class=\"zp_table\"><tbody><tr><th><span style=\"color: #2470cc;\">Shared Line<\/span><\/th><td>Nomor telepon dapat dibagikan dalam grup, dan berbagai fungsi telepon seperti membuat dan menerima panggilan serta pesan suara dapat dibagikan.<\/td><\/tr><tr><th><span style=\"color: #2470cc;\">Call Queue<\/span><\/th><td>Buat grup untuk panggilan masuk tertentu. Anda dapat mengatur aturan panggilan dalam grup sesuai dengan penggunaan Anda.<\/td><\/tr><tr><th><span style=\"color: #2470cc;\">Call forwarding<\/span><\/th><td>Secara otomatis meneruskan panggilan tertentu ke orang yang ditunjuk atau nomor eksternal<\/td><\/tr><tr><th><span style=\"color: #2470cc;\">Automated Response (IVR)<\/span><\/th><td>Siapkan petugas otomatis dengan berbagai aturan untuk mengarahkan panggilan ke antrean, ekstensi, atau pesan suara secara efisien<\/td><\/tr><tr><th><span style=\"color: #2470cc;\">Call forwarding<\/span><\/th><td>Transfer panggilan ke agen dengan mudah di mana saja, kapan saja<\/td><\/tr><tr><th><span style=\"color: #2470cc;\">on hold<\/span><\/th><td>Lanjutkan panggilan yang tertunda dengan mudah menggunakan aplikasi Zoom dan telepon meja yang mendukung Zoom Phone<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fa0fdfa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fa0fdfa\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b4d8190\" data-id=\"b4d8190\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f897596 elementor-widget elementor-widget-text-editor\" data-id=\"f897596\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"http:\/\/vcube.com\">V-cube Inc.<\/a> | <a href=\"https:\/\/vcube.co.id\/\">V-cube Indonesia<\/a> | Zoom Phone<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c993550 elementor-widget elementor-widget-spacer\" data-id=\"c993550\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-126683e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"126683e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e9cd663\" data-id=\"e9cd663\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78cdc90 elementor-widget elementor-widget-heading\" data-id=\"78cdc90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Inquiry Form<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fcfd22d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"fcfd22d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3d9be77 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3d9be77\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5403972\" data-id=\"5403972\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-170ceaf fluentform-widget-submit-button-custom elementor-widget elementor-widget-fluent-form-widget\" data-id=\"170ceaf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"fluent-form-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n            <div class=\"fluentform-widget-wrapper fluentform-widget-align-default\">\n\n            \n            <div class='fluentform ff-default fluentform_wrapper_1 ffs_default_wrap'><form data-form_id=\"1\" id=\"fluentform_1\" class=\"frm-fluent-form fluent_form_1 ff-el-form-top ff_form_instance_1_1 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_1_1\" method=\"POST\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">Web Inquiry Form<\/legend><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"ak_\"><label>&#916;<textarea name=\"ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"ak_js\" value=\"183\"\/><script>\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><input type='hidden' name='__fluent_form_embded_post_id' value='7226' \/><input type=\"hidden\" id=\"_fluentform_1_fluentformnonce\" name=\"_fluentform_1_fluentformnonce\" value=\"0ee623fad2\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/en\/wp-json\/wp\/v2\/pages\/7226\" \/><div data-type=\"name-element\" data-name=\"names\" class=\" ff-field_container ff-name-field-wrapper\" ><div class='ff-t-container'><div class='ff-t-cell '><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_1_names_first_name_' id='label_ff_1_names_first_name_' >Nama Depan<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"names[first_name]\" id=\"ff_1_names_first_name_\" class=\"ff-el-form-control\" placeholder=\"First Name\" aria-invalid=\"false\" aria-required=false><\/div><\/div><\/div><div class='ff-t-cell '><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_1_names_last_name_' id='label_ff_1_names_last_name_' >Nama Belakang<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"names[last_name]\" id=\"ff_1_names_last_name_\" class=\"ff-el-form-control\" placeholder=\"Last Name\" aria-invalid=\"false\" aria-required=false><\/div><\/div><\/div><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_1_input_text' id='label_ff_1_input_text' aria-label=\"Nama Perusahaan\">Nama Perusahaan<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"input_text\" class=\"ff-el-form-control\" placeholder=\"Company Name\" data-name=\"input_text\" id=\"ff_1_input_text\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_1_email' id='label_ff_1_email' aria-label=\"Alamat Email\">Alamat Email<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_1_email\" class=\"ff-el-form-control\" placeholder=\"Work Email\" data-name=\"email\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_1_numeric_field' id='label_ff_1_numeric_field' aria-label=\"Nomor Telepon\">Nomor Telepon<\/label><\/div><div class='ff-el-input--content'><input type=\"number\" name=\"numeric_field\" id=\"ff_1_numeric_field\" class=\"ff-el-form-control\" placeholder=\"WhatsApp\" data-name=\"numeric_field\" inputmode=\"numeric\" step=\"any\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_1_dropdown' id='label_ff_1_dropdown' aria-label=\"Pilih Informasi\">Pilih Informasi<\/label><\/div><div class='ff-el-input--content'><select name=\"dropdown\" id=\"ff_1_dropdown\" class=\"ff-el-form-control\" data-name=\"dropdown\" data-calc_value=\"0\"  aria-invalid=\"false\" aria-required=\"true\" aria-labelledby=\"label_ff_1_dropdown\"><option value=\"\">- Product and Services -<\/option><option value=\"WizLearn Learning Management System\"  >WizLearn Learning Management System<\/option><option value=\"Qumu (Enterprise Video Platform)\"  >Qumu (Enterprise Video Platform)<\/option><option value=\"Agora.io (Video SDK)\"  >Agora.io (Video SDK)<\/option><option value=\"EventIn\"  >EventIn<\/option><option value=\"Virtual and Hybrid Event\"  >Virtual and Hybrid Event<\/option><option value=\"Virtual Exhibition\"  >Virtual Exhibition<\/option><option value=\"Virtual Tour 360\u00b0\"  >Virtual Tour 360\u00b0<\/option><option value=\"Mediasite\"  >Mediasite<\/option><option value=\"V-CUBE Seminar\"  >V-CUBE Seminar<\/option><option value=\"Zoom (min 10 Host)\"  >Zoom (min 10 Host)<\/option><option value=\"Enavle\"  >Enavle<\/option><\/select><\/div><\/div><div class='ff-el-group has-conditions'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_1_dropdown_1' id='label_ff_1_dropdown_1' aria-label=\"Pilih Jenis Event Anda\">Pilih Jenis Event Anda<\/label><\/div><div class='ff-el-input--content'><select name=\"dropdown_1\" id=\"ff_1_dropdown_1\" class=\"ff-el-form-control\" data-name=\"dropdown_1\" data-calc_value=\"0\"  aria-invalid=\"false\" aria-required=\"false\" aria-labelledby=\"label_ff_1_dropdown_1\"><option value=\"\">- Event Type -<\/option><option value=\"Seminar \/ Webinar\"  >Seminar \/ Webinar<\/option><option value=\"Symposium\"  >Symposium<\/option><option value=\"RUPS \/ Public Expose\"  >RUPS \/ Public Expose<\/option><option value=\"General Event\"  >General Event<\/option><option value=\"Workshop\"  >Workshop<\/option><option value=\"Discussion Panel\"  >Discussion Panel<\/option><option value=\"Event Lainnya\"  >Event Lainnya<\/option><\/select><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_1_message' id='label_ff_1_message' aria-label=\"Pesan Anda\">Pesan Anda<\/label><\/div><div class='ff-el-input--content'><textarea aria-required=\"true\" aria-labelledby=\"label_ff_1_message\" name=\"message\" id=\"ff_1_message\" class=\"ff-el-form-control\" placeholder=\"Your Message\" rows=\"4\" cols=\"2\" data-name=\"message\" ><\/textarea><\/div><\/div><div class='ff-el-group ' ><div class='ff-el-input--content'><div data-fluent_id='1' name='g-recaptcha-response'><div\n\t\tdata-sitekey='6LcfPMwcAAAAAH-AiNTiRe31wV1LZBZ6L82MDmYV'\n\t\tid='fluentform-recaptcha-1-1'\n\t\tclass='ff-el-recaptcha g-recaptcha'\n\t\tdata-callback='fluentFormrecaptchaSuccessCallback'><\/div><\/div><\/div><\/div><div class='ff-el-group ff-text-left ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-md ff_btn_style\"  aria-label=\"Submit Form\">Submit Form<\/button><\/div><\/fieldset><\/form><div id='fluentform_1_errors' class='ff-errors-in-stack ff_form_instance_1_1 ff-form-loading_errors ff_form_instance_1_1_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_1_1 = {\"id\":\"1\",\"ajaxUrl\":\"https:\\\/\\\/vcube.co.id\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"cssClassName\":\"\",\"asteriskPlacement\":\"asterisk-right\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_1_1\",\"form_id_selector\":\"fluentform_1\",\"rules\":{\"names[first_name]\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"This field is required\"}},\"names[middle_name]\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"This field is required\"}},\"names[last_name]\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"This field is required\"}},\"input_text\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"This field is required\",\"global\":true}},\"email\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"This field is required\"},\"email\":{\"value\":true,\"message\":\"This field must contain a valid email\",\"global\":false,\"global_message\":\"This field must contain a valid email\"}},\"numeric_field\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"This field is required\",\"global\":true},\"numeric\":{\"value\":true,\"message\":\"This field must contain numeric value\",\"global_message\":\"This field must contain numeric value\",\"global\":true},\"min\":{\"value\":\"\",\"message\":\"Validation fails for minimum value\",\"global_message\":\"Validation fails for minimum value\",\"global\":true},\"max\":{\"value\":\"\",\"message\":\"Validation fails for maximum value\",\"global_message\":\"Validation fails for maximum value\",\"global\":true},\"digits\":{\"value\":\"\",\"message\":\"Validation fails for limited digits\",\"global_message\":\"Validation fails for limited digits\",\"global\":true}},\"dropdown\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global_message\":\"This field is required\",\"global\":true}},\"dropdown_1\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global_message\":\"This field is required\",\"global\":true}},\"message\":{\"required\":{\"value\":true,\"message\":\"This field is required\",\"global\":false,\"global_message\":\"This field is required\"}},\"g-recaptcha-response\":[]},\"debounce_time\":300,\"conditionals\":{\"dropdown_1\":{\"type\":\"any\",\"status\":true,\"conditions\":[{\"field\":\"dropdown\",\"value\":\"Virtual and Hybrid Event\",\"operator\":\"=\"}]}}};\n                            <\/script>\n                        <\/div>\n\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Zoom Phone Cloud PBX \/ Layanan Telepon Cloud Zoom Phone Panggilan telepon berkualitas tinggi dan beragam fitur. Wujudkan era baru telepon bisnis sambil menekan biaya. Selengkapnya Saya ingin mengurangi biaya peralatan terkait telepon Saya ingin mengganti operator tanpa mengubah nomor telepon saya Membangun basis, ingin menggunakan layanan telepon dengan biaya rendah Saya tidak dapat menjawab [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7241,"parent":1154,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"content-type":"","_joinchat":[],"footnotes":""},"class_list":["post-7226","page","type-page","status-publish","has-post-thumbnail","hentry"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zoom Phone | Cloud PBX | V-cube Indonesia<\/title>\n<meta name=\"description\" content=\"Zoom Phone adalah sistem telepon berbasis cloud yang dirancang untuk mendukung komunikasi bisnis dengan lebih efisien dan fleksibel\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vcube.co.id\/en\/zoom\/phone\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zoom Phone | Cloud PBX | V-cube Indonesia\" \/>\n<meta property=\"og:description\" content=\"Zoom Phone adalah sistem telepon berbasis cloud yang dirancang untuk mendukung komunikasi bisnis dengan lebih efisien dan fleksibel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vcube.co.id\/en\/zoom\/phone\/\" \/>\n<meta property=\"og:site_name\" content=\"V-cube Indonesia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/VcubeID\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-10T01:52:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-menghemat-Biaya.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"317\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"Zoom Phone adalah sistem telepon berbasis cloud yang dirancang untuk mendukung komunikasi bisnis dengan lebih efisien dan fleksibel\" \/>\n<meta name=\"twitter:site\" content=\"@VcubeID\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vcube.co.id\\\/zoom\\\/phone\\\/\",\"url\":\"https:\\\/\\\/vcube.co.id\\\/zoom\\\/phone\\\/\",\"name\":\"Zoom Phone | Cloud PBX | V-cube Indonesia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vcube.co.id\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vcube.co.id\\\/zoom\\\/phone\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vcube.co.id\\\/zoom\\\/phone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vcube.co.id\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Zoom-Phone-menghemat-Biaya.png\",\"datePublished\":\"2025-03-14T03:18:44+00:00\",\"dateModified\":\"2026-04-10T01:52:21+00:00\",\"description\":\"Zoom Phone adalah sistem telepon berbasis cloud yang dirancang untuk mendukung komunikasi bisnis dengan lebih efisien dan fleksibel\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vcube.co.id\\\/zoom\\\/phone\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vcube.co.id\\\/zoom\\\/phone\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/vcube.co.id\\\/zoom\\\/phone\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vcube.co.id\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Zoom-Phone-menghemat-Biaya.png\",\"contentUrl\":\"https:\\\/\\\/vcube.co.id\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Zoom-Phone-menghemat-Biaya.png\",\"width\":500,\"height\":317,\"caption\":\"Zoom Phone - menghemat Biaya\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vcube.co.id\\\/zoom\\\/phone\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vcube.co.id\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zoom\",\"item\":\"https:\\\/\\\/vcube.co.id\\\/zoom\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Zoom Phone\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vcube.co.id\\\/#website\",\"url\":\"https:\\\/\\\/vcube.co.id\\\/\",\"name\":\"V-cube Indonesia\",\"description\":\"Solusi Lengkap untuk komunikasi Visual dan LMS\",\"publisher\":{\"@id\":\"https:\\\/\\\/vcube.co.id\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vcube.co.id\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vcube.co.id\\\/#organization\",\"name\":\"V-cube Indonesia\",\"url\":\"https:\\\/\\\/vcube.co.id\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/vcube.co.id\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vcube.co.id\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/v-cube-beyond-telework.png\",\"contentUrl\":\"https:\\\/\\\/vcube.co.id\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/v-cube-beyond-telework.png\",\"width\":250,\"height\":71,\"caption\":\"V-cube Indonesia\"},\"image\":{\"@id\":\"https:\\\/\\\/vcube.co.id\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/VcubeID\\\/\",\"https:\\\/\\\/x.com\\\/VcubeID\",\"https:\\\/\\\/www.instagram.com\\\/vcubeid\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zoom Phone | Cloud PBX | V-cube Indonesia","description":"Zoom Phone adalah sistem telepon berbasis cloud yang dirancang untuk mendukung komunikasi bisnis dengan lebih efisien dan fleksibel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vcube.co.id\/en\/zoom\/phone\/","og_locale":"en_US","og_type":"article","og_title":"Zoom Phone | Cloud PBX | V-cube Indonesia","og_description":"Zoom Phone adalah sistem telepon berbasis cloud yang dirancang untuk mendukung komunikasi bisnis dengan lebih efisien dan fleksibel","og_url":"https:\/\/vcube.co.id\/en\/zoom\/phone\/","og_site_name":"V-cube Indonesia","article_publisher":"https:\/\/web.facebook.com\/VcubeID\/","article_modified_time":"2026-04-10T01:52:21+00:00","og_image":[{"width":500,"height":317,"url":"https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-menghemat-Biaya.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_description":"Zoom Phone adalah sistem telepon berbasis cloud yang dirancang untuk mendukung komunikasi bisnis dengan lebih efisien dan fleksibel","twitter_site":"@VcubeID","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/vcube.co.id\/zoom\/phone\/","url":"https:\/\/vcube.co.id\/zoom\/phone\/","name":"Zoom Phone | Cloud PBX | V-cube Indonesia","isPartOf":{"@id":"https:\/\/vcube.co.id\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vcube.co.id\/zoom\/phone\/#primaryimage"},"image":{"@id":"https:\/\/vcube.co.id\/zoom\/phone\/#primaryimage"},"thumbnailUrl":"https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-menghemat-Biaya.png","datePublished":"2025-03-14T03:18:44+00:00","dateModified":"2026-04-10T01:52:21+00:00","description":"Zoom Phone adalah sistem telepon berbasis cloud yang dirancang untuk mendukung komunikasi bisnis dengan lebih efisien dan fleksibel","breadcrumb":{"@id":"https:\/\/vcube.co.id\/zoom\/phone\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vcube.co.id\/zoom\/phone\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/vcube.co.id\/zoom\/phone\/#primaryimage","url":"https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-menghemat-Biaya.png","contentUrl":"https:\/\/vcube.co.id\/wp-content\/uploads\/2025\/03\/Zoom-Phone-menghemat-Biaya.png","width":500,"height":317,"caption":"Zoom Phone - menghemat Biaya"},{"@type":"BreadcrumbList","@id":"https:\/\/vcube.co.id\/zoom\/phone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vcube.co.id\/"},{"@type":"ListItem","position":2,"name":"Zoom","item":"https:\/\/vcube.co.id\/zoom\/"},{"@type":"ListItem","position":3,"name":"Zoom Phone"}]},{"@type":"WebSite","@id":"https:\/\/vcube.co.id\/#website","url":"https:\/\/vcube.co.id\/","name":"V-cube Indonesia","description":"Solusi Lengkap untuk komunikasi Visual dan LMS","publisher":{"@id":"https:\/\/vcube.co.id\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vcube.co.id\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/vcube.co.id\/#organization","name":"V-cube Indonesia","url":"https:\/\/vcube.co.id\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/vcube.co.id\/#\/schema\/logo\/image\/","url":"https:\/\/vcube.co.id\/wp-content\/uploads\/2021\/01\/v-cube-beyond-telework.png","contentUrl":"https:\/\/vcube.co.id\/wp-content\/uploads\/2021\/01\/v-cube-beyond-telework.png","width":250,"height":71,"caption":"V-cube Indonesia"},"image":{"@id":"https:\/\/vcube.co.id\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/VcubeID\/","https:\/\/x.com\/VcubeID","https:\/\/www.instagram.com\/vcubeid"]}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/PbtsIP-1Sy","post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/vcube.co.id\/en\/wp-json\/wp\/v2\/pages\/7226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vcube.co.id\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/vcube.co.id\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/vcube.co.id\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/vcube.co.id\/en\/wp-json\/wp\/v2\/comments?post=7226"}],"version-history":[{"count":61,"href":"https:\/\/vcube.co.id\/en\/wp-json\/wp\/v2\/pages\/7226\/revisions"}],"predecessor-version":[{"id":8195,"href":"https:\/\/vcube.co.id\/en\/wp-json\/wp\/v2\/pages\/7226\/revisions\/8195"}],"up":[{"embeddable":true,"href":"https:\/\/vcube.co.id\/en\/wp-json\/wp\/v2\/pages\/1154"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vcube.co.id\/en\/wp-json\/wp\/v2\/media\/7241"}],"wp:attachment":[{"href":"https:\/\/vcube.co.id\/en\/wp-json\/wp\/v2\/media?parent=7226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}